{"id":7398,"date":"2023-04-23T11:14:21","date_gmt":"2023-04-23T10:14:21","guid":{"rendered":"https:\/\/www.psc-psoe.es\/?p=7398"},"modified":"2023-04-23T11:14:21","modified_gmt":"2023-04-23T10:14:21","slug":"zuloaga-cantabria-no-puede-perder-mas-oportunidades-nuestro-potencial-deportivo-es-clave-para-el-desarrollo-sostenible","status":"publish","type":"post","link":"https:\/\/www.psc-psoe.es\/index.php\/2023\/04\/23\/zuloaga-cantabria-no-puede-perder-mas-oportunidades-nuestro-potencial-deportivo-es-clave-para-el-desarrollo-sostenible\/","title":{"rendered":"Zuloaga: \u201cCantabria no puede perder m\u00e1s oportunidades: nuestro potencial deportivo es clave para el desarrollo sostenible\u201d"},"content":{"rendered":"<p><strong>Santander, 23 de abril de 2023.<\/strong>\u00a0El secretario general del PSC-PSOE y candidato a presidente de Cantabria, Pablo Zuloaga, ha manifestado que \u201cCantabria no puede perder m\u00e1s oportunidades, ya que nuestro potencial deportivo es clave para el desarrollo sostenible\u201d.<\/p>\n<p>As\u00ed lo ha manifestado Zuloaga tras participar este domingo en la \u201cpotente prueba deportiva\u201d de las Rodadas de San Miguel de Aguayo, junto a Mario Iglesias, y el alcalde del municipio, Eduardo Guti\u00e9rrez. \u201cPruebas que son sin\u00f3nimo de desarrollo sostenible, de generaci\u00f3n de econom\u00eda y empleo\u201d, ha aclarado.<\/p>\n<p>Asimismo, ha manifestado su \u201ccompromiso por seguir fomentando la llegada de grandes eventos y pruebas deportivas a Cantabria, que fomenten la econom\u00eda y el empleo como la Vuelta a Espa\u00f1a; la selecci\u00f3n espa\u00f1ola de f\u00fatbol; el World P\u00e1del Tour; el campeonato de Espa\u00f1a de Remo Ol\u00edmpico: la Copa del Rey de Balonmano y la Copa del Rey de Vela\u201d.<\/p>\n<p>Una cita en la que el candidato a presidente de Cantabria ha explicado que \u201ccada vez son m\u00e1s los municipios c\u00e1ntabros, como San Miguel de Aguayo, los que aprovechan el impulso de las importantes citas deportivas para atraer m\u00e1s visitantes, generar m\u00e1s empleo y conseguir mayor visibilidad\u201d.<\/p>\n<p>En este sentido, Zuloaga ha detallado que \u201ctras la m\u00edtica meta de la Vuelta Ciclista a Espa\u00f1a, como es el Pico Jano, desde el Ayuntamiento han aprovechado el impulso que da el deporte, fomentando las oportunidades de desarrollo y as\u00ed cada d\u00eda son m\u00e1s los aficionados que se acercan a conocer este maravilloso municipio\u201d.<\/p>\n<p>Uno de tantos ejemplos, ha subrayado Zuloaga, de impulso al deporte \u201clo hacemos en el Pantano del Ebro, construyendo ya el que ser\u00e1 el mayor y mejor campo de regatas de Espa\u00f1a\u201d, ha asegurado Zuloaga. \u201cEn una oportunidad que permite que el Pantano del Ebro sea revulsivo econ\u00f3mico y generador de empleo, a trav\u00e9s de la econom\u00eda sostenible\u201d, ha declarado.<\/p>\n<p>El l\u00edder de los socialistas de Cantabria ha expuesto que \u201ccada una de las comarcas de Cantabria; Li\u00e9bana, Saja-Nansa, Alto As\u00f3n\u2026 aprovechamos el contexto para desarrollar nuevas oportunidades que dinamicen la actividad econ\u00f3mica y potencien el desarrollo sostenible\u201d.<\/p>\n<p>Una l\u00ednea de actuaciones que, ha descrito \u201ccomo parte de mi compromiso con Cantabria\u201d. A trav\u00e9s del \u201cfomento el deporte de alta monta\u00f1a, la escalada, el desarrollo de nuevas V\u00edas Ferratas, de circuitos BTT -como los que hemos desarrollado en Campoo o en la zona de Cabu\u00e9rniga-\u201d, ha asegurado, \u201cconseguiremos que el deporte se sit\u00fae como generador de atracci\u00f3n de visitantes a Cantabria, generador de econom\u00eda y de empleo de forma sostenible\u201d.<\/p>\n<p><strong>Impulso a nuestro deporte aut\u00f3ctono: los bolos<\/strong><\/p>\n<p>Adem\u00e1s, Pablo Zuloaga ha destacado el compromiso \u201cde fomentar el deporte sello de identidad de Cantabria: los bolos\u201d, a trav\u00e9s de \u201cun plan director cuyo objetivo es la renovaci\u00f3n y conservaci\u00f3n de las boleras de nuestra tierra\u201d, ha explicado.<\/p>\n<p>En palabras de Zuloaga, \u201ctras haber rehabilitado medio centenar de boleras en los \u00faltimos dos a\u00f1os en Cantabria, no vamos a permitir que se pierda ninguna bolera de nuestra regi\u00f3n por desatenci\u00f3n municipal\u201d.<\/p>\n<p>Las boleras, a ojos del socialista, \u201cson se\u00f1a de identidad de Cantabria y su memoria es la memoria de nuestros pueblos y espacios urbanos\u201d, ha sentenciado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santander, 23 de abril de 2023.\u00a0El secretario general del PSC-PSOE y candidato a presidente de Cantabria, Pablo Zuloaga, ha manifestado que \u201cCantabria no puede perder m\u00e1s oportunidades, ya que nuestro potencial deportivo es clave para el desarrollo sostenible\u201d. As\u00ed lo ha manifestado Zuloaga tras participar este domingo en la \u201cpotente prueba deportiva\u201d de las Rodadas [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7399,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[14,25],"tags":[],"class_list":["post-7398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa","category-actualidad"],"_links":{"self":[{"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/posts\/7398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/comments?post=7398"}],"version-history":[{"count":0,"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/posts\/7398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/media\/7399"}],"wp:attachment":[{"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/media?parent=7398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/categories?post=7398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psc-psoe.es\/index.php\/wp-json\/wp\/v2\/tags?post=7398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}